{"id":8243,"date":"2021-01-17T10:41:43","date_gmt":"2021-01-17T09:41:43","guid":{"rendered":"https:\/\/www.erotravel.de\/contact-us\/"},"modified":"2023-09-29T22:07:45","modified_gmt":"2023-09-29T20:07:45","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.erotravel.de\/en\/contact-us\/","title":{"rendered":"Contact us for more infos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">How to reach us: For questions, requests or\/and suggestions please write us via the <a href=\"#Kontaktformular\">contact form <\/a>below. Of course, we are also available by phone or Whatsapp. We are happy to help and look forward to hearing from you.<\/p>\n\n\n<style>.kb-row-layout-id8243_b36ce2-8a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8243_b36ce2-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8243_b36ce2-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8243_b36ce2-8a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8243_b36ce2-8a > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8243_b36ce2-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8243_b36ce2-8a alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8243_f4db48-94 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column8243_f4db48-94 > .kt-inside-inner-col,.kadence-column8243_f4db48-94 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8243_f4db48-94 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8243_f4db48-94 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8243_f4db48-94 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8243_f4db48-94 > .kt-inside-inner-col{background-color:var(--theme-palette-color-8, #ffffff);}.kadence-column8243_f4db48-94 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8243_f4db48-94{position:relative;}@media all and (max-width: 1024px){.kadence-column8243_f4db48-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8243_f4db48-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8243_f4db48-94 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e, .wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e[data-kb-block=\"kb-adv-heading8243_310ca1-5e\"]{font-size:25px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e[data-kb-block=\"kb-adv-heading8243_310ca1-5e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8243_310ca1-5e[data-kb-block=\"kb-adv-heading8243_310ca1-5e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading8243_310ca1-5e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8243_310ca1-5e\">Premium Newsletter<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nothing more to miss? Always be informed? Then register now for the free premium newsletter.<\/p>\n\n\n\n\t\t\t<form id=\"sib_signup_form_1\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.erotravel.de\/wp-includes\/images\/spinner.gif\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"1\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Bitte dieses Feld ausf\u00fcllen\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Bitte \u00fcberpr\u00fcfen Sie Ihre Email-Adresse\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"42757b4c84\">\n\t\t\t\t<div class=\"sib_signup_box_inside_1\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                    \t\t\t\t\t<p class=\"sib-email-area\">\r\n    <label class=\"sib-email-area\">Email*<\/label><br \/>\r\n    <input type=\"email\" class=\"sib-email-area\" name=\"email\" required=\"required\">\r\n<\/p>\r\n<p class=\"sib-NAME-area\">\r\n    <label class=\"sib-NAME-area\">Name (alternativ Profilname bei Joyclub, SDC, Spicymatch)<\/label><br \/>\r\n    <input type=\"text\" class=\"sib-NAME-area\" name=\"NAME\">\r\n<\/p><br>\r\n<p>Ihre Angaben aus dem Formular werden zum Versenden des Newsletters erhoben und verarbeitet. Sie k\u00f6nnen Ihre Einwilligung jederzeit per Email an <a>service@erotravel.de<\/a> oder in jedem Newsletter widerrufen.<p \/>\r\n<input type=\"checkbox\" name=\"terms\" required=\"required\"> Ich akzeptiere die <a href=\"https:\/\/www.erotravel.de\/datenschutz\/\">Datenschutzerkl\u00e4rung<\/a> \r\n<br><br>\r\n    <input type=\"submit\" class=\"sib-default-btn\" value=\"Eintragen\">\r\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_1 { padding: 5px; -moz-box-sizing:border-box; -webkit-box-sizing: border-box; box-sizing: border-box; } form#sib_signup_form_1 input[type=text],form#sib_signup_form_1 input[type=email], form#sib_signup_form_1 select { width: 100%; border: 1px solid #bbb; height: auto; margin: 5px 0 0 0; color:#000000; } form#sib_signup_form_1 .sib-default-btn { margin: 5px 0; padding: 6px 12px; color:#000; background-color: #999; border-color: #2E2E2E; font-size: 14px; font-weight:400; line-height: 1.4285; text-align: center; cursor: pointer; vertical-align: middle; -webkit-user-select:none; -moz-user-select:none; -ms-user-select:none; user-select:none; white-space: normal; border:1px solid transparent; border-radius: 3px; width:100%; } form#sib_signup_form_1 .sib-default-btn:hover { background-color: #444; } form#sib_signup_form_1 p{ margin: 10px 0 0 0; } form#sib_signup_form_1 a:hover{ color: #1770b8; }form#sib_signup_form_1 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_1 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_1 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_1 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t\n<\/div><\/div>\n\n\n<style>.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col,.kadence-column8243_f00e0c-74 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{background-color:var(--theme-palette-color-8, #ffffff);}.kadence-column8243_f00e0c-74 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8243_f00e0c-74{position:relative;}@media all and (max-width: 1024px){.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8243_f00e0c-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8243_f00e0c-74 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4, .wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4[data-kb-block=\"kb-adv-heading8243_21b023-b4\"]{font-size:25px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4[data-kb-block=\"kb-adv-heading8243_21b023-b4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8243_21b023-b4[data-kb-block=\"kb-adv-heading8243_21b023-b4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading8243_21b023-b4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8243_21b023-b4\">Facebook, Instagram, Youtube<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">We are also happy to be reached via Facebook, Instagram or Youtube and look forward to your Like.<br><\/p>\n\n\n\n<ul class=\"wp-block-social-links is-style-default is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/erotravel.de\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-instagram wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/erotravel.official\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-youtube wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/channel\/UCccG5URfxjEi_51C-AqYh6A\/featured\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M21.8,8.001c0,0-0.195-1.378-0.795-1.985c-0.76-0.797-1.613-0.801-2.004-0.847c-2.799-0.202-6.997-0.202-6.997-0.202 h-0.009c0,0-4.198,0-6.997,0.202C4.608,5.216,3.756,5.22,2.995,6.016C2.395,6.623,2.2,8.001,2.2,8.001S2,9.62,2,11.238v1.517 c0,1.618,0.2,3.237,0.2,3.237s0.195,1.378,0.795,1.985c0.761,0.797,1.76,0.771,2.205,0.855c1.6,0.153,6.8,0.201,6.8,0.201 s4.203-0.006,7.001-0.209c0.391-0.047,1.243-0.051,2.004-0.847c0.6-0.607,0.795-1.985,0.795-1.985s0.2-1.618,0.2-3.237v-1.517 C22,9.62,21.8,8.001,21.8,8.001z M9.935,14.594l-0.001-5.62l5.404,2.82L9.935,14.594z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">YouTube<\/span><\/a><\/li><\/ul>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c, .wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c[data-kb-block=\"kb-adv-heading8243_fde203-7c\"]{font-size:25px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c[data-kb-block=\"kb-adv-heading8243_fde203-7c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8243_fde203-7c[data-kb-block=\"kb-adv-heading8243_fde203-7c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading8243_fde203-7c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8243_fde203-7c\">Whatsapp and Telegram<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">For the so-called &#8220;Breaking News&#8221; we also use, for example, a Whatsapp &amp; a Telegram service.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IMPORTANT: For <strong>Whatsapp VIP info<\/strong> please save our mobile number (+49 170 494 2727) as contact and send us a Whatsapp with &#8220;Erotravel yes&#8221; and the first name and profile name of e.g. JOYclub, Spicymatch or SDC.<\/p>\n\n\n<style>.wp-block-kadence-icon.kt-svg-icons8243_7aa237-8e{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8243_7aa237-8e alignleft\"><style>.kt-svg-item-8243_98379c-40 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8243_98379c-40 .kb-svg-icon-wrap{color:#0aac5d;font-size:36px;margin-bottom:10px;}.kt-svg-item-8243_98379c-40:hover .kb-svg-icon-wrap{color:var(--theme-palette-color-3, #3A4F66);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-8243_98379c-40\"><a href=\" https:\/\/wa.me\/491704942727?text=Erotravel%20ja\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-icon-whatsapp1\"><svg viewBox=\"0 0 1024 1024\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M746.581 613.632c-12.843-6.4-75.392-36.992-87.040-41.216-11.648-4.309-20.181-6.4-28.715 6.4-8.405 12.587-32.896 41.131-40.277 49.579-7.467 8.32-14.891 8.96-27.563 3.2-12.8-6.4-53.888-19.84-102.528-63.36-37.888-33.92-63.317-75.52-70.827-88.32-7.424-12.8-0.811-19.84 5.547-26.24 5.803-5.76 12.843-14.72 19.243-22.315 6.229-7.723 8.277-12.843 12.672-21.163 4.267-8.96 2.091-16-1.067-22.357-3.2-6.4-28.672-69.12-39.339-94.123-10.24-24.917-20.779-21.76-28.672-21.76-7.339-0.64-15.829-0.64-24.363-0.64s-22.315 3.157-34.005 15.317c-11.648 12.8-44.587 43.52-44.587 105.6s45.653 122.24 52.011 131.2c6.357 8.32 89.813 136.32 217.6 191.36 30.464 12.8 54.187 20.48 72.704 26.837 30.464 9.685 58.24 8.32 80.213 5.163 24.491-3.883 75.392-30.763 86.016-60.843 10.88-30.080 10.88-55.040 7.68-60.8-3.157-5.76-11.52-8.96-24.32-14.72zM514.603 928h-0.683c-75.52 0-150.357-20.48-215.68-58.88l-15.36-9.131-160 41.6 42.88-155.52-10.197-16c-42.24-67.243-64.683-144.683-64.683-224.427 0-232.32 190.080-421.76 424.192-421.76 113.237 0 219.52 44.16 299.563 124.16 80 79.317 124.117 185.6 124.117 298.24-0.171 232.277-190.293 421.76-423.893 421.76zM875.52 147.157c-97.28-94.037-225.28-147.157-361.6-147.157-280.832 0-509.483 227.584-509.611 507.435 0 89.429 23.424 176.64 68.053 253.653l-72.363 262.912 270.293-70.485c74.496 40.235 158.293 61.611 243.627 61.739h0.256c280.96 0 509.696-227.669 509.824-507.563 0-135.509-52.907-263.040-149.12-358.869z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/wa.me\/491704942727?text=Erotravel%20ja\">+49 170 494 2727<\/a><\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-8243_7b9ddc-fd .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-8243_7b9ddc-fd .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--theme-palette-color-8, #ffffff);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-8243_7b9ddc-fd\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">On Telegram please <a href=\"https:\/\/t.me\/erotravel\" target=\"_blank\" rel=\"noreferrer noopener\">follow<\/a> the <a href=\"https:\/\/t.me\/erotravel\" target=\"_blank\" rel=\"noreferrer noopener\">Erotravel Telegram channel<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-telegram wp-block-social-link\"><a href=\"https:\/\/t.me\/erotravel\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 128 128\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M28.9700376,63.3244248 C47.6273373,55.1957357 60.0684594,49.8368063 66.2934036,47.2476366 C84.0668845,39.855031 87.7600616,38.5708563 90.1672227,38.528 C90.6966555,38.5191258 91.8804274,38.6503351 92.6472251,39.2725385 C93.294694,39.7979149 93.4728387,40.5076237 93.5580865,41.0057381 C93.6433345,41.5038525 93.7494885,42.63857 93.6651041,43.5252052 C92.7019529,53.6451182 88.5344133,78.2034783 86.4142057,89.5379542 C85.5170662,94.3339958 83.750571,95.9420841 82.0403991,96.0994568 C78.3237996,96.4414641 75.5015827,93.6432685 71.9018743,91.2836143 C66.2690414,87.5912212 63.0868492,85.2926952 57.6192095,81.6896017 C51.3004058,77.5256038 55.3966232,75.2369981 58.9976911,71.4967761 C59.9401076,70.5179421 76.3155302,55.6232293 76.6324771,54.2720454 C76.6721165,54.1030573 76.7089039,53.4731496 76.3346867,53.1405352 C75.9604695,52.8079208 75.4081573,52.921662 75.0095933,53.0121213 C74.444641,53.1403447 65.4461175,59.0880351 48.0140228,70.8551922 C45.4598218,72.6091037 43.1463059,73.4636682 41.0734751,73.4188859 C38.7883453,73.3695169 34.3926725,72.1268388 31.1249416,71.0646282 C27.1169366,69.7617838 23.931454,69.0729605 24.208838,66.8603276 C24.3533167,65.7078514 25.9403832,64.5292172 28.9700376,63.3244248 Z\" \/><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Telegram<\/span><\/a><\/li><\/ul>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8243_b63493-63 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8243_b63493-63 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8243_b63493-63 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;margin-left:auto;margin-right:auto;padding-top:25px;padding-right:0px;padding-bottom:25px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8243_b63493-63 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8243_b63493-63 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8243_b63493-63 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8243_b63493-63 alignfull wp-block-kadence-rowlayout\" id=\"Kontaktformular\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col,.kadence-column8243_cd28a4-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{background-color:var(--theme-palette-color-8, #ffffff);}.kadence-column8243_cd28a4-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8243_cd28a4-83{position:relative;}.kadence-column8243_cd28a4-83, .kt-inside-inner-col > .kadence-column8243_cd28a4-83:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8243_cd28a4-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8243_cd28a4-83 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd, .wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd[data-kb-block=\"kb-adv-heading8243_c85a10-fd\"]{font-size:25px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd[data-kb-block=\"kb-adv-heading8243_c85a10-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8243_c85a10-fd[data-kb-block=\"kb-adv-heading8243_c85a10-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading8243_c85a10-fd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8243_c85a10-fd\">Contact form<\/h2>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-6837af95-c4d9-44b2-91f9-e9c805d681c3 wpforms-render-modern\" id=\"wpforms-5534\"><form id=\"wpforms-form-5534\" class=\"wpforms-validate wpforms-form\" data-formid=\"5534\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/8243\" data-token=\"be38259363af36893143f8fcb8d875a5\" data-token-time=\"1788336012\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-5534-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-5534-field_0\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-5534-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" aria-errormessage=\"wpforms-5534-field_0-error\" required><\/div><div id=\"wpforms-5534-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-5534-field_1\">E-Mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-5534-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-5534-field_1-error\" required><\/div><div id=\"wpforms-5534-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-5534-field_6\">Phone<\/label><input type=\"text\" id=\"wpforms-5534-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-5534-field_6-error\" aria-describedby=\"wpforms-5534-field_6-description\" ><div id=\"wpforms-5534-field_6-description\" class=\"wpforms-field-description\">We may also contact you by phone or whatsapp?<\/div><\/div><div id=\"wpforms-5534-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-5534-field_4\">Subject<\/label><input type=\"text\" id=\"wpforms-5534-field_4\" class=\"wpforms-field-large\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-5534-field_4-error\" ><\/div><div id=\"wpforms-5534-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-5534-field_2\">Comment or message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-5534-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-5534-field_2-error\" required><\/textarea><\/div><div id=\"wpforms-5534-field_7-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-type=\"radio\" data-field-id=\"7\"><fieldset><legend class=\"wpforms-field-label\">Info \/ Newsletter \/ Premium List<\/legend><ul id=\"wpforms-5534-field_7\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-5534-field_7_1\" name=\"wpforms[fields][7]\" value=\"Email Newsletter\" aria-errormessage=\"wpforms-5534-field_7_1-error\" aria-describedby=\"wpforms-5534-field_7-description\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5534-field_7_1\">Email Newsletter<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-5534-field_7_2\" name=\"wpforms[fields][7]\" value=\"Whatsapp\" aria-errormessage=\"wpforms-5534-field_7_2-error\" aria-describedby=\"wpforms-5534-field_7-description\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5534-field_7_2\">Whatsapp<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-5534-field_7_3\" name=\"wpforms[fields][7]\" value=\"Telegram\" aria-errormessage=\"wpforms-5534-field_7_3-error\" aria-describedby=\"wpforms-5534-field_7-description\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5534-field_7_3\">Telegram<\/label><\/li><\/ul><div id=\"wpforms-5534-field_7-description\" class=\"wpforms-field-description\">You want to be always informed and not miss any exciting news &amp; current information from the travel world ? Then please select your favorite way.<\/div><\/fieldset><\/div><div id=\"wpforms-5534-field_5-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"5\"><fieldset><legend class=\"wpforms-field-label\">Note <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-5534-field_5\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-5534-field_5_1\" name=\"wpforms[fields][5][]\" value=\"I agree\" aria-errormessage=\"wpforms-5534-field_5_1-error\" aria-describedby=\"wpforms-5534-field_5-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5534-field_5_1\">I agree<\/label><\/li><\/ul><div id=\"wpforms-5534-field_5-description\" class=\"wpforms-field-description\">&#8230;that my details from the contact form are collected and processed to answer my question. The data will be deleted after the processing of your request is completed.  Note: You can revoke your consent for the future at any time by emailing mail@erotravel.de. Detailed information on the handling of user data can be found in our privacy policy.<\/div><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" ><div class=\"g-recaptcha\" data-sitekey=\"6Lc5K5gaAAAAAPvwf_WkUVI0MwydhvAauCTLhQ6i\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"5534\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/pages\/8243\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5534\" class=\"wpforms-submit\" data-alt-text=\"Send...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div>\n\n\n<style>.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{display:flex;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col,.kadence-column8243_9d6322-f0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8243_9d6322-f0{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{background-color:var(--theme-palette-color-8, #ffffff);}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8243_9d6322-f0{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8243_9d6322-f0{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8243_9d6322-f0{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8243_9d6322-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8243_9d6322-f0 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68, .wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68[data-kb-block=\"kb-adv-heading8243_59a708-68\"]{font-size:25px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68[data-kb-block=\"kb-adv-heading8243_59a708-68\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8243_59a708-68[data-kb-block=\"kb-adv-heading8243_59a708-68\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading8243_59a708-68 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8243_59a708-68\">Erotravel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Marc-Oliver Ziehbold<br>C. sa comuna 15<br>E-07650 Santanyi<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marc-Oliver Ziehbold<br>Kantstr. 9<br>56355 Nast\u00e4tten<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mobile: +49 170 4942727<br><a href=\"http:\/\/E-Mail:%20service@erotravel.de\">E-mail: service@erotravel.de<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>How to reach us: For questions, requests or\/and suggestions please write us via the contact form below. Of course, we are also available by phone or Whatsapp. We are happy [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11870,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_24":"","footnotes":""},"class_list":["post-8243","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"[data-prefix=\"single_page\"] .entry-header .page-title {--theme-font-size:30px;--theme-heading-color:var(--theme-palette-color-1);} [data-prefix=\"single_page\"] .entry-header .entry-meta {--theme-font-weight:600;--theme-text-transform:uppercase;--theme-font-size:12px;--theme-line-height:1.3;} [data-prefix=\"single_page\"] .hero-section[data-type=\"type-1\"] {--alignment:center;--margin-bottom:40px;}","tablet":"","mobile":""},"google_fonts":{"Open Sans":["n4","n6"]},"version":7},"page_title_panel":"","has_hero_section":"enabled","33cd94939cbbb07011af39a63c7bff57":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Startseite"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"Von","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"Am","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"Am","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"88ddf3b921328fe28eb739dd1cb8962a":"","hero_alignment1":{"desktop":"center","tablet":"center","mobile":"center","__changed":[]},"hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","b61e43a3018b5601d58a84f7269d24e7":"","hero_structure":"narrow","3120886cd7ce1b9dbf8fc603fdf99552":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"1bbf26d8c04a1c111592c6509adad0ce":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"var(--theme-palette-color-1)"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"e5e94548624fa06fced9f6a6f69dc53e":"","page_structure_type":"default","c44481be2817ce113da3d187e7d7ab78":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"inherit","content_area_spacing":"both","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"a9edbf93d8cdbb447beab06fa784547f":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Contact us for more infos - Erotravel<\/title>\n<meta name=\"description\" content=\"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erotravel.de\/en\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact us for more infos\" \/>\n<meta property=\"og:description\" content=\"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erotravel.de\/en\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Erotravel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erotravel.de\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T20:07:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@erotravel_de\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/\",\"url\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/\",\"name\":\"Contact us for more infos - Erotravel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.erotravel.de\\\/wp-content\\\/uploads\\\/contact-3994013_1920.webp\",\"datePublished\":\"2021-01-17T09:41:43+00:00\",\"dateModified\":\"2023-09-29T20:07:45+00:00\",\"description\":\"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.erotravel.de\\\/wp-content\\\/uploads\\\/contact-3994013_1920.webp\",\"contentUrl\":\"https:\\\/\\\/www.erotravel.de\\\/wp-content\\\/uploads\\\/contact-3994013_1920.webp\",\"width\":1440,\"height\":530,\"caption\":\"Kontakt Erotravel Email Whatsapp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/contact-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact us for more infos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/\",\"name\":\"Erotravel\",\"description\":\"Erotik Reisen, Swingerurlaub, Kreuzfahrten, FKK Resorts &amp; Hotels\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#organization\",\"name\":\"Erotravel\",\"url\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.erotravel.de\\\/wp-content\\\/uploads\\\/logo_erotravel_e_claim_01.webp\",\"contentUrl\":\"https:\\\/\\\/www.erotravel.de\\\/wp-content\\\/uploads\\\/logo_erotravel_e_claim_01.webp\",\"width\":1385,\"height\":329,\"caption\":\"Erotravel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.erotravel.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erotravel.de\\\/\",\"https:\\\/\\\/x.com\\\/erotravel_de\",\"https:\\\/\\\/www.instagram.com\\\/lust_auf_reisen.erotravel\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contact us for more infos - Erotravel","description":"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erotravel.de\/en\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact us for more infos","og_description":"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel","og_url":"https:\/\/www.erotravel.de\/en\/contact-us\/","og_site_name":"Erotravel","article_publisher":"https:\/\/www.facebook.com\/erotravel.de\/","article_modified_time":"2023-09-29T20:07:45+00:00","twitter_card":"summary_large_image","twitter_site":"@erotravel_de","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erotravel.de\/en\/contact-us\/","url":"https:\/\/www.erotravel.de\/en\/contact-us\/","name":"Contact us for more infos - Erotravel","isPartOf":{"@id":"https:\/\/www.erotravel.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erotravel.de\/en\/contact-us\/#primaryimage"},"image":{"@id":"https:\/\/www.erotravel.de\/en\/contact-us\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erotravel.de\/wp-content\/uploads\/contact-3994013_1920.webp","datePublished":"2021-01-17T09:41:43+00:00","dateModified":"2023-09-29T20:07:45+00:00","description":"Questions or wishes? We are here for you. Easy and fast to contact us directly - this is also Erotravel","breadcrumb":{"@id":"https:\/\/www.erotravel.de\/en\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erotravel.de\/en\/contact-us\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erotravel.de\/en\/contact-us\/#primaryimage","url":"https:\/\/www.erotravel.de\/wp-content\/uploads\/contact-3994013_1920.webp","contentUrl":"https:\/\/www.erotravel.de\/wp-content\/uploads\/contact-3994013_1920.webp","width":1440,"height":530,"caption":"Kontakt Erotravel Email Whatsapp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erotravel.de\/en\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.erotravel.de\/en\/"},{"@type":"ListItem","position":2,"name":"Contact us for more infos"}]},{"@type":"WebSite","@id":"https:\/\/www.erotravel.de\/en\/#website","url":"https:\/\/www.erotravel.de\/en\/","name":"Erotravel","description":"Erotik Reisen, Swingerurlaub, Kreuzfahrten, FKK Resorts &amp; Hotels","publisher":{"@id":"https:\/\/www.erotravel.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erotravel.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erotravel.de\/en\/#organization","name":"Erotravel","url":"https:\/\/www.erotravel.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erotravel.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.erotravel.de\/wp-content\/uploads\/logo_erotravel_e_claim_01.webp","contentUrl":"https:\/\/www.erotravel.de\/wp-content\/uploads\/logo_erotravel_e_claim_01.webp","width":1385,"height":329,"caption":"Erotravel"},"image":{"@id":"https:\/\/www.erotravel.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erotravel.de\/","https:\/\/x.com\/erotravel_de","https:\/\/www.instagram.com\/lust_auf_reisen.erotravel"]}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.erotravel.de\/wp-content\/uploads\/contact-3994013_1920-1024x377.webp",1024,377,true],"author_info":{"display_name":"admin","author_link":"https:\/\/www.erotravel.de\/en\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/pages\/8243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/comments?post=8243"}],"version-history":[{"count":0,"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/pages\/8243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/media\/11870"}],"wp:attachment":[{"href":"https:\/\/www.erotravel.de\/en\/wp-json\/wp\/v2\/media?parent=8243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}